{"id":12741,"date":"2018-10-04T00:00:00","date_gmt":"2018-10-04T00:00:00","guid":{"rendered":"https:\/\/basquetgirona.com\/?post_type=noticia&#038;p=12741"},"modified":"2023-10-20T09:29:09","modified_gmt":"2023-10-20T09:29:09","slug":"el-camino-empieza-en-alicante","status":"publish","type":"noticia","link":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/","title":{"rendered":"El camino empieza en Alicante"},"content":{"rendered":"<p>El senior del B&agrave;squet Girona viaja esta tarde hacia Alicante, donde ma&ntilde;ana viernes disputar&aacute; el partido inaugural del grupo Este de la LEB Plata de este a&ntilde;o. All&iacute;, el equipo dirigido por Quim Costa se ver&aacute; las caras en el pabell&oacute;n Pedro Ferr&aacute;ndiz con uno de los equipos m&aacute;s potentes de la categor&iacute;a, dise&ntilde;ado para subir (20.45 h).<\/p>\n<p>El HLA Alicante se qued&oacute; muy cerca del ascenso a LEB Oro la temporada pasada. De hecho, perdi&oacute; el quinto y decisivo partido de la final en casa contra el Real Canoe. A pesar del desencanto, el club se ha reforzado a conciencia durante el verano para que esta temporada sea la buena. Pedro Rivero, reci&eacute;n retirado, es el entrenador y ha apostado por hacer cambios importantes en la plantilla, con s&oacute;lo tres jugadores que contin&uacute;an (Nacho D&iacute;az, Kingsley Obiekwe y Boubacar Sidibe). De los ocho fichajes, destacan la pareja de bases -el eslovaco Vladimir Nemcok (NCAA-II) y el gerundense Quique Garrido (Pal&egrave;ncia, Oro), que estar&aacute; listo despu&eacute;s de superar una lesi&oacute;n en un gemelo- y las incorporaciones en el juego interior. Sobre todo, las del ala-p&iacute;vot guineano Cheick Conde (15,4 puntos y 6,5 rebotes con el Mor&oacute;n el curso pasado) y el cubano Georvys El&iacute;as (Albacete). En la pretemporada, han sido capaces de derrotar a dos rivales de LEB Oro, el Iberojet Palma (69-58) y el Tau Castell&oacute;n (86-78).<\/p>\n<p>* La valoraci&oacute;n de Quim Costa:<\/p>\n<p><em>&#8220;El Alicante ha hecho una buena pretemporada, derrotando a equipos de LEB Oro. Es un equipo s&oacute;lido, estable y de buen nivel f&iacute;sico. Adem&aacute;s, supongo que en su pista todav&iacute;a ser&aacute; m&aacute;s dif&iacute;cil de vencer. Tendremos que intentar jugar al m&aacute;ximo nivel que tenemos ahora para poder llevarnos la victoria&#8221;.<\/em><\/p>\n<p><em>&#8220;No conozco a&uacute;n con profundidad el resto de equipos del grupo para evaluar nuestro nivel. Nosotros estamos en fase de construcci&oacute;n. Pero pondremos toda la ilusi&oacute;n, trabajo y esfuerzo para intentar acabar entre los seis primeros e ir al grupo de arriba. Persistiremos&#8221;.<\/em><\/p>\n<p><a href=\"http:\/\/www.lebplata.es\/resultados.aspx\">Los horarios de la 1a jornada<\/a><\/p>\n<p><em>Foto: Sergi Geron&egrave;s<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El senior debuta en la LEB Plata ma&ntilde;ana viernes visitando la pista del HLA Alicante (20.45 h), uno de los favoritos al ascenso<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","categoria_noticia":[],"class_list":["post-12741","noticia","type-noticia","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El camino empieza en Alicante - Basquet Girona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El camino empieza en Alicante - Basquet Girona\" \/>\n<meta property=\"og:description\" content=\"El senior debuta en la LEB Plata ma&ntilde;ana viernes visitando la pista del HLA Alicante (20.45 h), uno de los favoritos al ascenso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/\" \/>\n<meta property=\"og:site_name\" content=\"Basquet Girona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BasquetGironaOficial\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T09:29:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BasquetGirona\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El camino empieza en Alicante - Basquet Girona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/","og_locale":"es_ES","og_type":"article","og_title":"El camino empieza en Alicante - Basquet Girona","og_description":"El senior debuta en la LEB Plata ma&ntilde;ana viernes visitando la pista del HLA Alicante (20.45 h), uno de los favoritos al ascenso","og_url":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/","og_site_name":"Basquet Girona","article_publisher":"https:\/\/www.facebook.com\/BasquetGironaOficial","article_modified_time":"2023-10-20T09:29:09+00:00","twitter_card":"summary_large_image","twitter_site":"@BasquetGirona","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/#article","isPartOf":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/"},"author":{"name":"wp6tems","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/23e2f6077a380ef4bcbafe12c1c99532"},"headline":"El camino empieza en Alicante","datePublished":"2018-10-04T00:00:00+00:00","dateModified":"2023-10-20T09:29:09+00:00","mainEntityOfPage":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/basquetgirona.com\/es\/#organization"},"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/","url":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/","name":"El camino empieza en Alicante - Basquet Girona","isPartOf":{"@id":"https:\/\/basquetgirona.com\/es\/#website"},"datePublished":"2018-10-04T00:00:00+00:00","dateModified":"2023-10-20T09:29:09+00:00","breadcrumb":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/basquetgirona.com\/es\/noticia\/el-camino-empieza-en-alicante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/basquetgirona.com\/es\/"},{"@type":"ListItem","position":2,"name":"El camino empieza en Alicante"}]},{"@type":"WebSite","@id":"https:\/\/basquetgirona.com\/es\/#website","url":"https:\/\/basquetgirona.com\/es\/","name":"Basquet Girona","description":"","publisher":{"@id":"https:\/\/basquetgirona.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basquetgirona.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/basquetgirona.com\/es\/#organization","name":"Basquet Girona","url":"https:\/\/basquetgirona.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2023\/02\/girona-logo1.png","contentUrl":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2023\/02\/girona-logo1.png","width":124,"height":136,"caption":"Basquet Girona"},"image":{"@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BasquetGironaOficial","https:\/\/twitter.com\/BasquetGirona","https:\/\/www.instagram.com\/basquetgirona\/","https:\/\/es.linkedin.com\/company\/bsquet-girona","https:\/\/www.tiktok.com\/@basquetgirona"]},{"@type":"Person","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/23e2f6077a380ef4bcbafe12c1c99532","name":"wp6tems","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bb7e7b41fd75599f16e2481d79259374553199dc2bee29aa20aa615e30729456?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb7e7b41fd75599f16e2481d79259374553199dc2bee29aa20aa615e30729456?s=96&d=mm&r=g","caption":"wp6tems"},"sameAs":["https:\/\/basquetgirona.com"],"url":"https:\/\/basquetgirona.com\/es\/author\/wp6tems\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/12741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/12741\/revisions"}],"predecessor-version":[{"id":15540,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/12741\/revisions\/15540"}],"wp:attachment":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/media?parent=12741"}],"wp:term":[{"taxonomy":"categoria_noticia","embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/categoria_noticia?post=12741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}