{"id":48492,"date":"2025-06-18T19:06:52","date_gmt":"2025-06-18T19:06:52","guid":{"rendered":"https:\/\/basquetgirona.com\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/"},"modified":"2025-10-03T18:49:19","modified_gmt":"2025-10-03T18:49:19","slug":"baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense","status":"publish","type":"noticia","link":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/","title":{"rendered":"Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense"},"content":{"rendered":"\n<p>Bajo el eslogan <strong>\n  <em>Unidos para seguir creciendo<\/em>\n<\/strong> , el <strong>Baloncesto Girona<\/strong> y <strong>Uni Girona<\/strong> han hecho oficial su unificaci\u00f3n en un acto hist\u00f3rico celebrado en Fontajau. Esta uni\u00f3n es fruto de un acuerdo profundo y comprometido entre dos clubes emblem\u00e1ticos, que representan la esencia y la pasi\u00f3n por el baloncesto en Girona. La ciudad ha vivido una jornada que marca el inicio de una nueva etapa para el baloncesto de la ciudad.  <\/p>\n\n<p>Un v\u00eddeo que repasaba momentos emblem\u00e1ticos de ambos clubs ha dado el pistoletazo de salida al acto con im\u00e1genes que ha repasado la historia de ambas entidades, la pieza ha servido para recordar de d\u00f3nde venimos y para reforzar el sentido profundo de la uni\u00f3n: la fuerza de una trayectoria compartida y de una ciudad que vive el baloncesto con pasi\u00f3n <strong>.<\/strong><\/p>\n\n<p><strong>UN PROYECTO CON VALORES<\/strong><br\/> Una conversaci\u00f3n entre Marc Gasol y Cayetano P\u00e9rez han desgranado los fundamentos de esta uni\u00f3n, que se articula como una apuesta estrat\u00e9gica y emocional, pensada para crecer de forma conjunta, con m\u00e1s fuerza y \u200b\u200bcon una estructura compartida.<br\/> Gasol ha subrayado que la integraci\u00f3n permite incorporar todos los activos del Uni Girona dentro del B\u00e0squet Girona. Una f\u00f3rmula que no implica la desaparici\u00f3n de Uni, sino que preserva su esencia, valores y legado, integrando parte de su junta directiva dentro del nuevo Consejo Asesor del club, donde el propio Cayetano P\u00e9rez ejercer\u00e1 como responsable del proyecto femenino. <br\/>Esta estructura permitir\u00e1 potenciar sinergias en \u00e1mbitos como la gesti\u00f3n, la log\u00edstica, la financiaci\u00f3n o la comunicaci\u00f3n, y fortalecer la marca \u201cGirona\u201d como referente deportivo. Gasol ha defendido que \u00e9ste es un paso para garantizar un modelo sostenible y competitivo, abierto a Europa ya nuevas oportunidades de patrocinio, con una gesti\u00f3n integral y profesionalizada. <\/p>\n\n<p><strong>REFORZAR LA IDENTIDAD, SUMAR AFICIONES<\/strong><br\/> Tanto Gasol como P\u00e9rez destacaron el papel de las aficiones en este nuevo camino. La voluntad es que todo el mundo se sienta part\u00edcipe y que el proyecto refleje la pasi\u00f3n y la identidad de la ciudad.<br\/> P\u00e9rez ha afirmado que esta unificaci\u00f3n representa una gran oportunidad para consolidar la viabilidad del proyecto femenino, competir al m\u00e1ximo nivel y hacerlo manteniendo el estilo y la proximidad que han definido Uni Girona. \u201cCompartimos sinergias. Llevamos a\u00f1os trabajando y el poder optimizar estos recursos nos ayudar\u00e1 a crecer. El femenino necesit\u00f3 un plus y este plus nos dar\u00e1 el poder estar juntos con el baloncesto girona. Esperamos que sigamos estando arriba y poder dar guerra\u201d.     <br\/>Gasol, por su parte, ha pedido un voto de confianza a aquellos seguidores que a\u00fan tengan dudas: \u201cNo se trata s\u00f3lo de resultados deportivos. Es una apuesta por los valores, por la uni\u00f3n, por sumar fuerzas y por construir un proyecto s\u00f3lido, reconocible y arraigado.\u201d<\/p>\n\n<p><strong>DE LA BASE A LA \u00c9LITE<\/strong><br\/> Esta uni\u00f3n culmina un camino iniciado hace tres temporadas con el trabajo conjunto en la base. La experiencia ha sido muy positiva y se ha convertido en el modelo de referencia para esta nueva etapa, donde ahora tambi\u00e9n los dos equipos profesionales formar\u00e1n parte de una misma estructura. empezar hace tres a\u00f1os y hoy\u201d, ha destacado Marc Gasol.<br\/> Con esta integraci\u00f3n, el club se equipara a otros grandes referentes estatales como Valencia Basket, Casademont Zaragoza o Club Joventut Badalona, \u200b\u200by se posiciona como un proyecto deportivo \u00fanico, comprometido con la formaci\u00f3n, la igualdad y la excelencia.  <\/p>\n\n<p><strong>EL FUTURO ES NUESTRO. JUNTOS SOMOS GIRONA <\/strong><br\/>Uno de los instantes m\u00e1s destacados del acto fue la proyecci\u00f3n del v\u00eddeo oficial de presentaci\u00f3n de la unificaci\u00f3n, que sirvi\u00f3 para poner imagen y emoci\u00f3n a este nuevo proyecto. Con un mensaje claro e inspirador -\u201cUnidos para seguir creciendo\u201d-, el v\u00eddeo ha culminado la puesta en escena de este nuevo camino compartido. <\/p>\n\n<p>El acto se ha cerrado con una sesi\u00f3n de fotograf\u00edas oficiales y un encuentro distendido entre todos los asistentes. Con este paso, Girona se dota de un \u00fanico proyecto deportivo de ciudad, con visi\u00f3n de futuro, arraigo en el territorio y una decidida apuesta por la formaci\u00f3n, la equidad y la excelencia. <\/p>\n\n<p><strong>Unidos para seguir creciendo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el eslogan Unidos para seguir creciendo , el Baloncesto Girona y Uni Girona han hecho oficial su unificaci\u00f3n en un acto hist\u00f3rico celebrado en Fontajau. Esta uni\u00f3n es fruto de un acuerdo profundo y comprometido entre dos clubes emblem\u00e1ticos, que representan la esencia y la pasi\u00f3n por el baloncesto en Girona. La ciudad ha [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":48488,"menu_order":0,"template":"","categoria_noticia":[190],"class_list":["post-48492","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","categoria_noticia-equipos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense - Basquet Girona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense - Basquet Girona\" \/>\n<meta property=\"og:description\" content=\"Bajo el eslogan Unidos para seguir creciendo , el Baloncesto Girona y Uni Girona han hecho oficial su unificaci\u00f3n en un acto hist\u00f3rico celebrado en Fontajau. Esta uni\u00f3n es fruto de un acuerdo profundo y comprometido entre dos clubes emblem\u00e1ticos, que representan la esencia y la pasi\u00f3n por el baloncesto en Girona. La ciudad ha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/\" \/>\n<meta property=\"og:site_name\" content=\"Basquet Girona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BasquetGironaOficial\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T18:49:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basquetgirona.com\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-19.58.47-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BasquetGirona\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense - Basquet Girona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/","og_locale":"es_ES","og_type":"article","og_title":"Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense - Basquet Girona","og_description":"Bajo el eslogan Unidos para seguir creciendo , el Baloncesto Girona y Uni Girona han hecho oficial su unificaci\u00f3n en un acto hist\u00f3rico celebrado en Fontajau. Esta uni\u00f3n es fruto de un acuerdo profundo y comprometido entre dos clubes emblem\u00e1ticos, que representan la esencia y la pasi\u00f3n por el baloncesto en Girona. La ciudad ha [&hellip;]","og_url":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/","og_site_name":"Basquet Girona","article_publisher":"https:\/\/www.facebook.com\/BasquetGironaOficial","article_modified_time":"2025-10-03T18:49:19+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-18-at-19.58.47-scaled.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@BasquetGirona","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/#article","isPartOf":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/"},"author":{"name":"Pau De Castro","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/9196efe7de3d62004e09ea79cd72b8d5"},"headline":"Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense","datePublished":"2025-06-18T19:06:52+00:00","dateModified":"2025-10-03T18:49:19+00:00","mainEntityOfPage":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/"},"wordCount":743,"publisher":{"@id":"https:\/\/basquetgirona.com\/es\/#organization"},"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/","url":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/","name":"Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense - Basquet Girona","isPartOf":{"@id":"https:\/\/basquetgirona.com\/es\/#website"},"datePublished":"2025-06-18T19:06:52+00:00","dateModified":"2025-10-03T18:49:19+00:00","breadcrumb":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/basquetgirona.com\/es\/noticia\/baloncesto-girona-y-uni-girona-oficializan-su-union-nace-un-proyecto-compartido-para-hacer-crecer-el-baloncesto-gerundense\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/basquetgirona.com\/es\/"},{"@type":"ListItem","position":2,"name":"Baloncesto Girona y Uni Girona oficializan su uni\u00f3n: Nace un proyecto compartido para hacer crecer el baloncesto gerundense"}]},{"@type":"WebSite","@id":"https:\/\/basquetgirona.com\/es\/#website","url":"https:\/\/basquetgirona.com\/es\/","name":"Basquet Girona","description":"","publisher":{"@id":"https:\/\/basquetgirona.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basquetgirona.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/basquetgirona.com\/es\/#organization","name":"Basquet Girona","url":"https:\/\/basquetgirona.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2023\/02\/girona-logo1.png","contentUrl":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2023\/02\/girona-logo1.png","width":124,"height":136,"caption":"Basquet Girona"},"image":{"@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BasquetGironaOficial","https:\/\/twitter.com\/BasquetGirona","https:\/\/www.instagram.com\/basquetgirona\/","https:\/\/es.linkedin.com\/company\/bsquet-girona","https:\/\/www.tiktok.com\/@basquetgirona"]},{"@type":"Person","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/9196efe7de3d62004e09ea79cd72b8d5","name":"Pau De Castro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/311a301e125ef9f088e17c727474e75fb5b82151095ccfc4b6e27ae4855b5814?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/311a301e125ef9f088e17c727474e75fb5b82151095ccfc4b6e27ae4855b5814?s=96&d=mm&r=g","caption":"Pau De Castro"},"url":"https:\/\/basquetgirona.com\/es\/author\/pdcastro\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/48492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":6,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/48492\/revisions"}],"predecessor-version":[{"id":56168,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/48492\/revisions\/56168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/media\/48488"}],"wp:attachment":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/media?parent=48492"}],"wp:term":[{"taxonomy":"categoria_noticia","embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/categoria_noticia?post=48492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}