{"id":53057,"date":"2025-08-19T09:00:13","date_gmt":"2025-08-19T09:00:13","guid":{"rendered":"https:\/\/basquetgirona.com\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/"},"modified":"2025-11-13T16:20:25","modified_gmt":"2025-11-13T16:20:25","slug":"mariam-coulibaly-potencia-interior-por-el-baloncesto-girona","status":"publish","type":"noticia","link":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/","title":{"rendered":"Mariam Coulibaly, potencia interior por el B\u00e0squet Girona"},"content":{"rendered":"\n<p><em>La jugadora m\u00e1s valorada de la \u00faltima LF Endesa refuerza el juego interior gerundense<\/em><\/p>\n\n<p>Mariam Coulibaly (Bamako, Mali; 07\/10\/1997) es nueva jugadora del Spar Girona para la pr\u00f3xima temporada. La p\u00edvot, de 192 cm y 27 a\u00f1os, llega procedente del Club Joventut Badalona, \u200b\u200bdonde ha firmado una de las temporadas m\u00e1s dominantes de su carrera. <\/p>\n\n<p>Coulibaly se form\u00f3 en el CB Islas Canarias, donde debut\u00f3 en la Liga Femenina en la temporada 2015-16. Posteriormente, fich\u00f3 por el Snatt&#8217;s Femenino Sant Adri\u00e0, con quien disput\u00f3 dos temporadas en la LF Endesa, consolid\u00e1ndose como una de las p\u00edvots j\u00f3venes con mayor proyecci\u00f3n del campeonato. En el 2019 dio el salto a Francia, jugando en el Landerneau, y al a\u00f1o siguiente volvi\u00f3 a la m\u00e1xima categor\u00eda estatal con el IDK Euskotren, donde jug\u00f3 durante cuatro temporadas antes de fichar, el pasado verano, por la Penya.  <\/p>\n\n<p>La temporada 2024-25, con el Club Joventut Badalona, \u200b\u200bha sido su mejor a nivel estad\u00edstico y de reconocimiento individual: 22 puntos por partido con un 61,6% en tiros de dos, 10,8 rebotes y una valoraci\u00f3n media de 29, liderando as\u00ed la liga en este apartado. Ha sido elegida MVP de la jornada hasta 12 veces en 30 jornadas, ha formado parte del mejor cinco ideal de la LF Endesa y ha competido con Bibby por el MVP final de la competici\u00f3n. <\/p>\n\n<p>Con este movimiento, el club sigue dando forma al nuevo proyecto deportivo del B\u00e0squet Girona para la temporada 2025-26, con Mariam Coulibaly como d\u00e9cima jugadora confirmada del Spar Girona.<\/p>\n\n<p><strong>Declaraciones de Pere Puig, director deportivo:<br\/><\/strong> &#8220;Con el fichaje de Coulibaly busc\u00e1bamos una p\u00edvot cl\u00e1sica, con presencia dentro de la pintura. Adem\u00e1s se a\u00f1ade una muy buena mano, que a\u00fan la hace m\u00e1s valiosa. Una jugadora experimentada en nuestra liga, aunque debutar\u00e1 en el EuroLeague Women, pero estamos convencidos de que nos har\u00e1 muy bien. alegre que busca Roberto tendr\u00e1n mayor eficiencia\u201d.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jugadora m\u00e1s valorada de la \u00faltima LF Endesa refuerza el juego interior gerundense Mariam Coulibaly (Bamako, Mali; 07\/10\/1997) es nueva jugadora del Spar Girona para la pr\u00f3xima temporada. La p\u00edvot, de 192 cm y 27 a\u00f1os, llega procedente del Club Joventut Badalona, \u200b\u200bdonde ha firmado una de las temporadas m\u00e1s dominantes de su carrera. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":53002,"menu_order":0,"template":"","categoria_noticia":[362],"class_list":["post-53057","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","categoria_noticia-spar-girona-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mariam Coulibaly, potencia interior por el B\u00e0squet Girona - Basquet Girona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mariam Coulibaly, potencia interior por el B\u00e0squet Girona - Basquet Girona\" \/>\n<meta property=\"og:description\" content=\"La jugadora m\u00e1s valorada de la \u00faltima LF Endesa refuerza el juego interior gerundense Mariam Coulibaly (Bamako, Mali; 07\/10\/1997) es nueva jugadora del Spar Girona para la pr\u00f3xima temporada. La p\u00edvot, de 192 cm y 27 a\u00f1os, llega procedente del Club Joventut Badalona, \u200b\u200bdonde ha firmado una de las temporadas m\u00e1s dominantes de su carrera. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Basquet Girona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BasquetGironaOficial\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T16:20:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/basquetgirona.com\/wp-content\/uploads\/2025\/08\/Captura-de-pantalla-2025-08-19-092915.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1431\" \/>\n\t<meta property=\"og:image:height\" content=\"873\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@BasquetGirona\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mariam Coulibaly, potencia interior por el B\u00e0squet Girona - Basquet Girona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/","og_locale":"es_ES","og_type":"article","og_title":"Mariam Coulibaly, potencia interior por el B\u00e0squet Girona - Basquet Girona","og_description":"La jugadora m\u00e1s valorada de la \u00faltima LF Endesa refuerza el juego interior gerundense Mariam Coulibaly (Bamako, Mali; 07\/10\/1997) es nueva jugadora del Spar Girona para la pr\u00f3xima temporada. La p\u00edvot, de 192 cm y 27 a\u00f1os, llega procedente del Club Joventut Badalona, \u200b\u200bdonde ha firmado una de las temporadas m\u00e1s dominantes de su carrera. [&hellip;]","og_url":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/","og_site_name":"Basquet Girona","article_publisher":"https:\/\/www.facebook.com\/BasquetGironaOficial","article_modified_time":"2025-11-13T16:20:25+00:00","og_image":[{"width":1431,"height":873,"url":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2025\/08\/Captura-de-pantalla-2025-08-19-092915.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@BasquetGirona","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/#article","isPartOf":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/"},"author":{"name":"wp6tems","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/23e2f6077a380ef4bcbafe12c1c99532"},"headline":"Mariam Coulibaly, potencia interior por el B\u00e0squet Girona","datePublished":"2025-08-19T09:00:13+00:00","dateModified":"2025-11-13T16:20:25+00:00","mainEntityOfPage":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/"},"wordCount":338,"commentCount":0,"publisher":{"@id":"https:\/\/basquetgirona.com\/es\/#organization"},"inLanguage":"es"},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/","url":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/","name":"Mariam Coulibaly, potencia interior por el B\u00e0squet Girona - Basquet Girona","isPartOf":{"@id":"https:\/\/basquetgirona.com\/es\/#website"},"datePublished":"2025-08-19T09:00:13+00:00","dateModified":"2025-11-13T16:20:25+00:00","breadcrumb":{"@id":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/basquetgirona.com\/es\/noticia\/mariam-coulibaly-potencia-interior-por-el-baloncesto-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/basquetgirona.com\/es\/"},{"@type":"ListItem","position":2,"name":"Mariam Coulibaly, potencia interior por el B\u00e0squet Girona"}]},{"@type":"WebSite","@id":"https:\/\/basquetgirona.com\/es\/#website","url":"https:\/\/basquetgirona.com\/es\/","name":"Basquet Girona","description":"","publisher":{"@id":"https:\/\/basquetgirona.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/basquetgirona.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/basquetgirona.com\/es\/#organization","name":"Basquet Girona","url":"https:\/\/basquetgirona.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2023\/02\/girona-logo1.png","contentUrl":"https:\/\/basquetgirona.com\/wp-content\/uploads\/2023\/02\/girona-logo1.png","width":124,"height":136,"caption":"Basquet Girona"},"image":{"@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BasquetGironaOficial","https:\/\/twitter.com\/BasquetGirona","https:\/\/www.instagram.com\/basquetgirona\/","https:\/\/es.linkedin.com\/company\/bsquet-girona","https:\/\/www.tiktok.com\/@basquetgirona"]},{"@type":"Person","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/23e2f6077a380ef4bcbafe12c1c99532","name":"wp6tems","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/basquetgirona.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bb7e7b41fd75599f16e2481d79259374553199dc2bee29aa20aa615e30729456?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb7e7b41fd75599f16e2481d79259374553199dc2bee29aa20aa615e30729456?s=96&d=mm&r=g","caption":"wp6tems"},"sameAs":["https:\/\/basquetgirona.com"],"url":"https:\/\/basquetgirona.com\/es\/author\/wp6tems\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/53057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/types\/noticia"}],"author":[{"embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/53057\/revisions"}],"predecessor-version":[{"id":57801,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/noticia\/53057\/revisions\/57801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/media\/53002"}],"wp:attachment":[{"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/media?parent=53057"}],"wp:term":[{"taxonomy":"categoria_noticia","embeddable":true,"href":"https:\/\/basquetgirona.com\/es\/wp-json\/wp\/v2\/categoria_noticia?post=53057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}